{"id":718,"date":"2025-11-07T11:12:21","date_gmt":"2025-11-07T11:12:21","guid":{"rendered":"https:\/\/pensionbreite1577.live-website.com\/?page_id=718"},"modified":"2025-12-02T12:32:31","modified_gmt":"2025-12-02T12:32:31","slug":"room-1","status":"publish","type":"page","link":"https:\/\/www.pension-breite.ch\/en\/room-1\/","title":{"rendered":"Room 1"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"718\" class=\"elementor elementor-718\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32b4c097 e-con-full e-flex e-con e-parent\" data-id=\"32b4c097\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2da787ab elementor-widget elementor-widget-text-editor\" data-id=\"2da787ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7869bc7 e-flex e-con-boxed e-con e-parent\" data-id=\"7869bc7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4ef9296 e-con-full e-flex e-con e-child\" data-id=\"4ef9296\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1498f52 elementor-widget elementor-widget-spacer\" data-id=\"1498f52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c99a08f elementor-widget elementor-widget-heading\" data-id=\"c99a08f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Unsere Zimmer\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df1bac2 elementor-widget elementor-widget-text-editor\" data-id=\"df1bac2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Bequeme Unterkunft mit allen Annehmlichkeiten f\u00fcr Ihren Aufenthalt<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-879456b elementor-widget elementor-widget-eael-breadcrumbs\" data-id=\"879456b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-breadcrumbs\">\n\t\t\t<div class=\"eael-breadcrumbs__content\"><a href=\"https:\/\/www.pension-breite.ch\/en\">Home<\/a> <span class=\"eael-breadcrumb-separator\">\/<\/span> <span class = \"eael-current\">Page<\/span><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84f7905 elementor-widget elementor-widget-spacer\" data-id=\"84f7905\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ded3e74 e-flex e-con-boxed e-con e-parent\" data-id=\"ded3e74\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5983f6c elementor-widget elementor-widget-spacer\" data-id=\"5983f6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f38849 e-con-full e-flex e-con e-child\" data-id=\"3f38849\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d471953 elementor-widget elementor-widget-heading\" data-id=\"d471953\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zimmer 1 \u2013 Doppelzimmer (Strassenseite)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2d5888 elementor-align-left elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-mobile-align-center bdt-navigation-type-arrows elementor-widget elementor-widget-bdt-slider\" data-id=\"e2d5888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-slider.default\">\n\t\t\t\t\t\t\t<div id=\"bdt-slider-e2d5888\" class=\"bdt-slider bdt-arrows-align-center\" data-settings=\"{&quot;autoplay&quot;:{&quot;delay&quot;:5000},&quot;loop&quot;:true,&quot;speed&quot;:500,&quot;effect&quot;:&quot;slide&quot;,&quot;fadeEffect&quot;:{&quot;crossFade&quot;:true},&quot;navigation&quot;:{&quot;nextEl&quot;:&quot;#bdt-slider-e2d5888 .bdt-navigation-next&quot;,&quot;prevEl&quot;:&quot;#bdt-slider-e2d5888 .bdt-navigation-prev&quot;},&quot;pagination&quot;:{&quot;el&quot;:&quot;#bdt-slider-e2d5888 .swiper-pagination&quot;,&quot;type&quot;:&quot;&quot;,&quot;clickable&quot;:&quot;true&quot;,&quot;dynamicBullets&quot;:false},&quot;scrollbar&quot;:{&quot;el&quot;:&quot;#bdt-slider-e2d5888 .swiper-scrollbar&quot;,&quot;hide&quot;:&quot;true&quot;}}\">\n\t\t\t<div class=\"swiper-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\" dir=\"ltr\">\n\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t<div class=\"bdt-slide-item swiper-slide bdt-slide-effect-left\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slider-image-wrapper\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0461-scaled.jpeg\" class=\"bdt-cover\" alt=\"\" data-bdt-cover=\"1\" srcset=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0461-scaled.jpeg 2560w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0461-300x200.jpeg 300w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0461-1024x683.jpeg 1024w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0461-768x512.jpeg 768w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0461-1536x1024.jpeg 1536w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0461-2048x1365.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-slide-desc bdt-position-large bdt-position-center-right bdt-position-z-index\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"bdt-slide-item swiper-slide bdt-slide-effect-left\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slider-image-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0481-scaled.jpeg\" class=\"bdt-cover\" alt=\"\" data-bdt-cover=\"1\" srcset=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0481-scaled.jpeg 2560w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0481-300x200.jpeg 300w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0481-1024x683.jpeg 1024w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0481-768x512.jpeg 768w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0481-1536x1024.jpeg 1536w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0481-2048x1365.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-slide-desc bdt-position-large bdt-position-center-right bdt-position-z-index\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"bdt-slide-item swiper-slide bdt-slide-effect-left\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slider-image-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0455-scaled.jpeg\" class=\"bdt-cover\" alt=\"\" data-bdt-cover=\"1\" srcset=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0455-scaled.jpeg 2560w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0455-300x200.jpeg 300w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0455-1024x683.jpeg 1024w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0455-768x512.jpeg 768w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0455-1536x1024.jpeg 1536w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0455-2048x1365.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-slide-desc bdt-position-large bdt-position-center-right bdt-position-z-index\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"bdt-slide-item swiper-slide bdt-slide-effect-left\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slider-image-wrapper\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0457-1-scaled.jpeg\" class=\"bdt-cover\" alt=\"\" data-bdt-cover=\"1\" srcset=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0457-1-scaled.jpeg 2560w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0457-1-300x200.jpeg 300w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0457-1-1024x683.jpeg 1024w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0457-1-768x512.jpeg 768w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0457-1-1536x1024.jpeg 1536w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0457-1-2048x1365.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-slide-desc bdt-position-large bdt-position-center-right bdt-position-z-index\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"bdt-position-z-index bdt-position-center bdt-visible@m\">\n\t\t\t\t<div class=\"bdt-arrows-container bdt-slidenav-container\">\n\t\t\t\t\t<a href=\"\" class=\"bdt-navigation-prev bdt-slidenav-previous bdt-icon bdt-slidenav\">\n\t\t\t\t\t\t<i class=\"ep-icon-arrow-left-0\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<a href=\"\" class=\"bdt-navigation-next bdt-slidenav-next bdt-icon bdt-slidenav\">\n\t\t\t\t\t\t<i class=\"ep-icon-arrow-right-0\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f642ab5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f642ab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"whitespace-normal break-words\">Treten Sie ein in Komfort und moderne Einfachheit mit Zimmer 1 im Pension Basel Einzelzimmer, einem durchdacht gestalteten Doppelzimmer, das Funktionalit\u00e4t, W\u00e4rme und Eleganz f\u00fcr einen wirklich angenehmen Aufenthalt vereint. Ideal f\u00fcr Paare, Gesch\u00e4ftsreisende oder Freunde, die sich eine Unterkunft teilen, bietet dieses Zimmer einen ruhigen R\u00fcckzugsort mit allen wesentlichen Annehmlichkeiten, die Sie f\u00fcr ein entspanntes Erlebnis ben\u00f6tigen.<\/p>\n<h5><br \/>Innenarchitektur und Design<\/h5>\n<p class=\"whitespace-normal break-words\">Dieses Einzelzimmer der Pension Basel zeichnet sich durch ein modernes, minimalistisches Design mit sanften neutralen T\u00f6nen, Holzb\u00f6den und geschmackvoller Dekoration aus, die eine einladende Atmosph\u00e4re schafft. Zwei Einzelbetten sind elegant zusammen arrangiert, um ein komfortables Doppelbett zu bilden, erg\u00e4nzt durch gem\u00fctliche Bettw\u00e4sche und stimmungsvolle Nachttischbeleuchtung f\u00fcr einen erholsamen Schlaf. Der Raum wird von nat\u00fcrlichem Tageslicht erhellt, das durch grosse Fenster str\u00f6mt und die luftige und erfrischende Atmosph\u00e4re verst\u00e4rkt.<\/p>\n<h5><br \/>Sitz- und Entspannungsbereich<\/h5>\n<p class=\"whitespace-normal break-words\">Entspannen Sie sich in der komfortablen Sitzecke unseres Pension Basel Einzelzimmers, ausgestattet mit zwei Sessel und einem Beistelltisch in Fenstern\u00e4he \u2014 perfekt zum Lesen, Geniessen Ihres Morgenkaffees oder einfach f\u00fcr einen ruhigen Moment f\u00fcr sich selbst. Dieser Bereich verleiht dem Raum eine heimelige Note und verwandelt ihn in eine kleine Oase der Entspannung.<br \/>Ausstattung und Ger\u00e4te<br \/>Jedes Detail in Zimmer 1 ist zu Ihrem Komfort gestaltet. G\u00e4ste werden finden:<\/p>\n<ul>\n<li>Ein Doppelbett mit pl\u00fcschiger Bettw\u00e4sche<\/li>\n<li>Ein ger\u00e4umiger Kleiderschrank, um die Sachen ordentlich zu organisieren.<\/li>\n<li>Eine Kaffeemaschine f\u00fcr einen frischen Br\u00fchkaffee zu jeder Tageszeit<\/li>\n<li>Ein kleiner K\u00fchlschrank zur Aufbewahrung von Getr\u00e4nken und Snacks<\/li>\n<li>Ein Flachbildfernseher zur Unterhaltung<\/li>\n<li>Kostenloses WLAN, um verbunden zu bleiben<\/li>\n<li>Ein gem\u00fctlicher Sitzbereich zum Entspannen oder Lesen<\/li>\n<\/ul>\n<p><br \/>Ob Sie gesch\u00e4ftlich oder privat unterwegs sind, die Annehmlichkeiten sorgen daf\u00fcr, dass Sie alles griffbereit haben.<br \/>Ambiente und Beleuchtung<\/p>\n<p class=\"whitespace-normal break-words\">Sanfte Beleuchtungsk\u00f6rper im gesamten Einzelzimmer der Pension Basel, einschliesslich Nachttischlampen und einer modernen Stehlampe, schaffen abends eine entspannende Atmosph\u00e4re. Die Einrichtung vereint Funktionalit\u00e4t und Stil und sorgt sowohl f\u00fcr Komfort als auch f\u00fcr ein Gef\u00fchl von Raffinesse.<\/p>\n<h5><br \/>Standort<\/h5>\n<p>Zimmer 1 befindet sich auf der Strassenseite und bietet einen authentischen Blick auf die Umgebung, w\u00e4hrend es durch gut passende Vorh\u00e4nge und schallisolierte W\u00e4nde Privatsph\u00e4re wahrt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8687b34 elementor-align-left elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"8687b34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/pension-breite.ch\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt buchen <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87df629 elementor-widget elementor-widget-spacer\" data-id=\"87df629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8803241 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"8803241\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb2e4b0 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"fb2e4b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0420-1024x683.jpeg\" class=\"attachment-large size-large wp-image-332\" alt=\"MG 0420 scaled\" srcset=\"https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0420-1024x683.jpeg 1024w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0420-300x200.jpeg 300w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0420-768x512.jpeg 768w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0420-1536x1024.jpeg 1536w, https:\/\/www.pension-breite.ch\/wp-content\/uploads\/2025\/10\/MG_0420-2048x1365.jpeg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Unsere Zimmer Bequeme Unterkunft mit allen Annehmlichkeiten f\u00fcr Ihren Aufenthalt Home \/ Page Zimmer 1 \u2013 Doppelzimmer (Strassenseite) Treten Sie ein in Komfort und moderne Einfachheit mit Zimmer 1 im Pension Basel Einzelzimmer, einem durchdacht gestalteten Doppelzimmer, das Funktionalit\u00e4t, W\u00e4rme und Eleganz f\u00fcr einen wirklich angenehmen Aufenthalt vereint. Ideal f\u00fcr Paare, Gesch\u00e4ftsreisende oder Freunde, die [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-718","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.pension-breite.ch\/en\/wp-json\/wp\/v2\/pages\/718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pension-breite.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pension-breite.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pension-breite.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pension-breite.ch\/en\/wp-json\/wp\/v2\/comments?post=718"}],"version-history":[{"count":13,"href":"https:\/\/www.pension-breite.ch\/en\/wp-json\/wp\/v2\/pages\/718\/revisions"}],"predecessor-version":[{"id":928,"href":"https:\/\/www.pension-breite.ch\/en\/wp-json\/wp\/v2\/pages\/718\/revisions\/928"}],"wp:attachment":[{"href":"https:\/\/www.pension-breite.ch\/en\/wp-json\/wp\/v2\/media?parent=718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6912e7551906362031274fef. Config Timestamp: 2025-11-11 07:35:48 UTC, Cached Timestamp: 2026-05-13 23:22:14 UTC -->